{"id":4815,"date":"2022-06-13T06:35:53","date_gmt":"2022-06-13T04:35:53","guid":{"rendered":"https:\/\/office-roxx.de\/buero-bewegung\/?p=4815"},"modified":"2022-06-12T22:59:53","modified_gmt":"2022-06-12T20:59:53","slug":"beim-bewegten-arbeiten-herrscht-stillstand","status":"publish","type":"post","link":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/","title":{"rendered":"Beim bewegten Arbeiten herrscht Stillstand"},"content":{"rendered":"<p><strong>Juni 2022<\/strong>. Vor einem Jahr haben wir, die Initiative \u201eBewegung im B\u00fcro\u201c, die Leserschaft des Blogs OFFICE ROXX gefragt: Wie halten Sie es mit der Bewegung bei der B\u00fcroarbeit? Die Ergebnisse waren teilweise alarmierend. Nun wurde diese Umfrage vom 2. bis 15. Mai 2022 in unserem Auftrag wiederholt. Leider besteht nun noch mehr Handlungsbedarf.<br \/>\n<!--more weiterlesen...--><\/p>\n<p>Die Auswertung der <a href=\"https:\/\/office-roxx.de\/2021\/06\/09\/zu-wenig-bewegung-im-homeoffice\/\" target=\"_blank\" rel=\"noopener\">Leserumfrage \u201eBewegung bei der B\u00fcroarbeit 2021\u201c<\/a> im vergangenen Mai zeigte deutlich: Fast zwei Drittel der Home-Worker bewegen sich daheim noch weniger als an einem regul\u00e4ren Arbeitstag im Firmenb\u00fcro. Im Office wurde im ersten Coronajahr zu viel gesessen, zu wenig gestanden und zu wenig gegangen. Daheim sah die Bilanz aber noch schlechter aus als im Firmenb\u00fcro. Doch hat sich die Situation mittlerweile verbessert? Wird sich jetzt mehr bewegt und wurde mehr in bewegungsf\u00f6rdernde L\u00f6sungen im Office und Homeoffice investiert?<\/p>\n<h2>Bewegung im Allgemeinen bleibt unzureichend<\/h2>\n<p>Die aktuellen Ergebnisse der repr\u00e4sentativen Leserumfrage sind ern\u00fcchternd: Mit dem Anteil, den k\u00f6rperliche Bewegung im eigenen Leben ausmacht, waren die \u00fcber 2.300 befragten B\u00fcrobesch\u00e4ftigten aus Deutschland nur m\u00e4\u00dfig zufrieden. Im Schnitt wurde die Schulnote 3,4 erreicht. Das entspricht in etwa dem Vorjahreswert von 3,5. Damit bleibt dies ein schlechtes Zeugnis f\u00fcr die Bewegung.<\/p>\n<h2>Zwei Drittel bewegen sich im Homeoffice weniger<\/h2>\n<p>W\u00e4hrend im ersten Jahr der Pandemie aufgrund der Vorjahresergebnisse der Homeoffice-Anteil an der eigenen B\u00fcroarbeit unter Office-Workern in Deutschland bei 62 Prozent lag, ist ein Gro\u00dfteil der Home-Worker im zweiten Coronajahr offenbar wieder ins B\u00fcro zur\u00fcckgekehrt. Der Anteil der Heimarbeit lag im Durchschnitt nur noch bei 44 Prozent.<\/p>\n<p>Doch wird sich an einem Arbeitstag im Homeoffice mehr oder weniger bewegt als an einem Tag im Firmenb\u00fcro? Weniger! Der Anteil ist gegen\u00fcber dem Vorjahr sogar noch gestiegen: 61 Prozent (2021: 57 Prozent) bewegen sich daheim weniger als im B\u00fcro. 39 Prozent (2021: 43 Prozent) bewegen sich nach eigenem Empfinden dagegen mehr als im Office.<\/p>\n<h2>Im Homeoffice wird noch mehr gesessen als im Office<\/h2>\n<p>Der von Experten empfohlene Haltungsmix bei der B\u00fcroarbeit lautet: 60 Prozent Sitzen, 30 Prozent Stehen und zehn Prozent Gehen. Die Umfrageteilnehmenden verbringen laut eigener Aussage aktuell im Schnitt 75 Prozent ihres Homeoffice-Tages im Sitzen, zehn Prozent im Stehen und f\u00fcnf Prozent mit Gehen \u2013 wenig Ver\u00e4nderungen im Vergleich zum Vorjahr: 73 Prozent im Sitzen, elf Prozent im Stehen und sieben Prozent mit Gehen.<\/p>\n<p>Im Office f\u00e4llt der Mix im Durchschnitt so aus: 64 Prozent Sitzen, 18 Prozent Stehen, 18 Prozent Gehen. In den Umfrage-Ergebnissen aus dem Jahr 2021 waren es noch 65 Prozent Sitzen, 18 Prozent Stehen, neun Prozent Gehen.<\/p>\n<p>\u201eNoch mehr B\u00fcrobesch\u00e4ftigte als im vorangegangenen Befragungszeitraum bewegen sich bei der Heimarbeit weniger als im B\u00fcro. Das ist ein ernstes Problem, vor allem vor dem Hintergrund der Homeoffice-Euphorie, die noch in vielen Bereichen vorherrscht. H\u00e4lt man sich vor Augen, wie wenig sich schon im B\u00fcro bewegt wird, wird klar, wie gro\u00df der Handlungsbedarf ist\u201c, so Dr. Robert Nehring, Sprecher der Initiative \u201eBewegung im B\u00fcro\u201c.<\/p>\n<h2>Homeoffice-Ausstattung l\u00e4sst zu w\u00fcnschen \u00fcbrig<\/h2>\n<p>Die Antworten auf die Frage \u201eWie ergonomisch bzw. bewegungsf\u00f6rdernd ist Ihr Arbeitsplatz im Homeoffice?\u201c ergaben im Schnitt die Schulnote 3,9 (2021: 3,7). In Bezug auf den Arbeitsplatz im B\u00fcro wurde hier eine Durchschnittsnote von 2,9 (Vorjahr: 3,3) erreicht. Ergonomie und Bewegungsf\u00f6rderung lassen weiterhin sehr zu w\u00fcnschen \u00fcbrig. Erwartungsgem\u00e4\u00df vor allem im Homeoffice. Erstaunlich ist, dass sich die Beurteilung hier sogar gegen\u00fcber dem Vorjahr verschlechtert hat. Vielleicht ist daheim aber auch das Bewusstsein f\u00fcr die notwendige Ergonomie und Bewegungsf\u00f6rderung gestiegen.<\/p>\n<p>Im Homeoffice verf\u00fcgen:<\/p>\n<ul>\n<li>18,7 Prozent \u00fcber eine Sitz-Steh-L\u00f6sung wie einen solchen Tisch, einen Tischaufsatz oder \u00c4hnliches (2021: 12,8 Prozent),<\/li>\n<li>30,3 Prozent \u00fcber einen ergonomischen bzw. bewegungsf\u00f6rdernden Stuhl (2021: 25,9 Prozent),<\/li>\n<li>8,2 Prozent \u00fcber beides (2021: 4,9 Prozent),<\/li>\n<li>7,1 Prozent \u00fcber eine weitere bewegungsf\u00f6rdernde L\u00f6sung wie etwa Stehhocker, Deskbike, Laufband, Balancebord, Fu\u00dfwippe etc. (2021: 4,1 Prozent) und<\/li>\n<li>3,3 Prozent \u00fcber alle drei M\u00f6glichkeiten (2021: 1,7 Prozent).<\/li>\n<\/ul>\n<p>Im Firmenb\u00fcro verf\u00fcgen:<\/p>\n<ul>\n<li>24,2 Prozent \u00fcber eine Sitz-Steh-L\u00f6sung (2021: 22,8 Prozent),<\/li>\n<li>40,5 Prozent \u00fcber einen ergonomischen bzw. bewegungsf\u00f6rdernden Stuhl (2021: 39,8 Prozent),<\/li>\n<li>21,1 Prozent \u00fcber beides (2021: 19,8 Prozent),<\/li>\n<li>6,1 Prozent \u00fcber eine weitere bewegungsf\u00f6rdernde L\u00f6sung (2021: 4,8 Prozent) und<\/li>\n<li>4,2 Prozent \u00fcber alle drei M\u00f6glichkeiten (2021: 1,4 Prozent).<\/li>\n<\/ul>\n<p>Dies best\u00e4tigt das Ergebnis des Vorjahres: Es gibt noch reichlich Handlungsbedarf in Bezug auf ergonomische bzw. bewegungsf\u00f6rdernde L\u00f6sungen, vor allem im Homeoffice. Allerdings geht die Entwicklung f\u00fcr Dr. Robert Nehring in die richtige Richtung: \u201eSowohl im Office als auch im Homeoffice ist gegen\u00fcber dem Vorjahr ein deutlicher Zuwachs an solchen L\u00f6sungen zu verzeichnen. Vor allem in den heimischen Arbeitsplatz wurde offenbar investiert, um die Gesundheit zu sch\u00fctzen und die Produktivit\u00e4t zu erh\u00f6hen.\u201c<\/p>\n<h2>F\u00fcr mehr Bewegung in Office und Homeoffice<\/h2>\n<p>Dass laut den Umfrage-Ergebnissen fast jeder Dritte (29 Prozent) beabsichtigt, in eine ergonomische bzw. bewegungsf\u00f6rdernde Ausstattung seines Homeoffice-Arbeitsplatzes zu investieren, ist ein gutes Zeichen. Die Steigerung gegen\u00fcber der Vorjahresbefragung um vier Prozent zeigt, dass Besch\u00e4ftigte auch zu Hause gesund und produktiv arbeiten wollen. Verbesserungspotenzial gibt es dennoch in allen Bereichen. Insbesondere gilt es zu beachten, dass bewegungsf\u00f6rdernde L\u00f6sungen auch noch ihrem Zweck entsprechend genutzt werden m\u00fcssen.<\/p>\n<p>\u201eIm Homeoffice ist nicht alles eitel Sonnenschein. Die Pandemie hat deutlich gezeigt, dass die heimischen vier W\u00e4nde nicht f\u00fcr jeden B\u00fcrobesch\u00e4ftigten der bessere Arbeitsort sind. Jeder Einzelne sollte vor allem da arbeiten, wo dies in Bezug auf seine Gesundheit, sein Wohlbefinden und seine Produktivit\u00e4t sowie im Einklang mit der Kultur und den Zielen des Arbeitgebers am besten m\u00f6glich ist\u201c, res\u00fcmiert Dr. Robert Nehring.<\/p>\n<p><strong>Zur Studie: 2.302 Teilnehmer, vor allem B\u00fcroangestellte<br \/>\n<\/strong>An der Umfrage haben 2.302 B\u00fcrobesch\u00e4ftigte aus Deutschland teilgenommen. 75,7 Prozent der Teilnehmenden waren B\u00fcroangestellte. 7,1 Prozent sind Selbstst\u00e4ndige und 6,4 Prozent geh\u00f6ren einer Gesch\u00e4ftsf\u00fchrung an. 10,8 Prozent arbeiten als B\u00fcroeink\u00e4ufer. Hier waren Mehrfachnennungen m\u00f6glich. Das Durchschnittsalter der Befragten betrug 43,3 Jahre. 50 Prozent sind m\u00e4nnlich, 49 Prozent weiblich, 1 Prozent divers.<\/p>\n<p>Entscheidungen in Bezug auf die B\u00fcroausstattung im Firmenoffice treffen 35,5 Prozent der Befragten, Entscheidungen in Bezug auf die Ausstattung des Homeoffices 79,2 Prozent. Die Gr\u00f6\u00dfe der Unternehmen, in denen die Umfrageteilnehmer arbeiten, wurde wie folgt angegeben: 25,2 Prozent 1\u201310 Besch\u00e4ftigte, 23,7 Prozent 11\u2013100, 19,7 Prozent 101\u2013500 und 31,4 Prozent 500 und mehr Besch\u00e4ftigte.<\/p>\n<p>Die vollst\u00e4ndige Auswertung der Befragung findet sich auf <a href=\"https:\/\/office-roxx.de\/2022\/06\/13\/stillstand-beim-bewegten-arbeiten\/\" target=\"_blank\" rel=\"noopener\">OFFICE-ROXX.DE<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juni 2022. Vor einem Jahr haben wir, die Initiative \u201eBewegung im B\u00fcro\u201c, die Leserschaft des Blogs OFFICE ROXX gefragt: Wie halten Sie es mit der Bewegung bei der B\u00fcroarbeit? Die Ergebnisse waren teilweise alarmierend. Nun wurde diese Umfrage vom 2. bis 15. Mai 2022 in unserem Auftrag wiederholt. Leider besteht nun noch mehr Handlungsbedarf.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4815","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beim bewegten Arbeiten herrscht Stillstand &#8211; BEWEGUNG IM B\u00dcRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beim bewegten Arbeiten herrscht Stillstand &#8211; BEWEGUNG IM B\u00dcRO\" \/>\n<meta property=\"og:description\" content=\"Juni 2022. Vor einem Jahr haben wir, die Initiative \u201eBewegung im B\u00fcro\u201c, die Leserschaft des Blogs OFFICE ROXX gefragt: Wie halten Sie es mit der Bewegung bei der B\u00fcroarbeit? Die Ergebnisse waren teilweise alarmierend. Nun wurde diese Umfrage vom 2. bis 15. Mai 2022 in unserem Auftrag wiederholt. Leider besteht nun noch mehr Handlungsbedarf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/\" \/>\n<meta property=\"og:site_name\" content=\"BEWEGUNG IM B\u00dcRO\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-13T04:35:53+00:00\" \/>\n<meta name=\"author\" content=\"Team-BB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Team-BB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/beim-bewegten-arbeiten-herrscht-stillstand\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/beim-bewegten-arbeiten-herrscht-stillstand\\\/\"},\"author\":{\"name\":\"Team-BB\",\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#\\\/schema\\\/person\\\/1fb790e36fc2c425645a8d6bdd301799\"},\"headline\":\"Beim bewegten Arbeiten herrscht Stillstand\",\"datePublished\":\"2022-06-13T04:35:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/beim-bewegten-arbeiten-herrscht-stillstand\\\/\"},\"wordCount\":1022,\"publisher\":{\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#organization\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/beim-bewegten-arbeiten-herrscht-stillstand\\\/\",\"url\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/beim-bewegten-arbeiten-herrscht-stillstand\\\/\",\"name\":\"Beim bewegten Arbeiten herrscht Stillstand &#8211; BEWEGUNG IM B\u00dcRO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#website\"},\"datePublished\":\"2022-06-13T04:35:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/beim-bewegten-arbeiten-herrscht-stillstand\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/beim-bewegten-arbeiten-herrscht-stillstand\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/beim-bewegten-arbeiten-herrscht-stillstand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beim bewegten Arbeiten herrscht Stillstand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#website\",\"url\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/\",\"name\":\"BEWEGUNG IM B\u00dcRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#organization\",\"name\":\"Bewegung im B\u00fcro\",\"url\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Bewegung.jpg\",\"contentUrl\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Bewegung.jpg\",\"width\":999,\"height\":520,\"caption\":\"Bewegung im B\u00fcro\"},\"image\":{\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/office-roxx.de\\\/buero-bewegung\\\/#\\\/schema\\\/person\\\/1fb790e36fc2c425645a8d6bdd301799\",\"name\":\"Team-BB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beim bewegten Arbeiten herrscht Stillstand &#8211; BEWEGUNG IM B\u00dcRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/","og_locale":"de_DE","og_type":"article","og_title":"Beim bewegten Arbeiten herrscht Stillstand &#8211; BEWEGUNG IM B\u00dcRO","og_description":"Juni 2022. Vor einem Jahr haben wir, die Initiative \u201eBewegung im B\u00fcro\u201c, die Leserschaft des Blogs OFFICE ROXX gefragt: Wie halten Sie es mit der Bewegung bei der B\u00fcroarbeit? Die Ergebnisse waren teilweise alarmierend. Nun wurde diese Umfrage vom 2. bis 15. Mai 2022 in unserem Auftrag wiederholt. Leider besteht nun noch mehr Handlungsbedarf.","og_url":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/","og_site_name":"BEWEGUNG IM B\u00dcRO","article_published_time":"2022-06-13T04:35:53+00:00","author":"Team-BB","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Team-BB","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/#article","isPartOf":{"@id":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/"},"author":{"name":"Team-BB","@id":"https:\/\/office-roxx.de\/buero-bewegung\/#\/schema\/person\/1fb790e36fc2c425645a8d6bdd301799"},"headline":"Beim bewegten Arbeiten herrscht Stillstand","datePublished":"2022-06-13T04:35:53+00:00","mainEntityOfPage":{"@id":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/"},"wordCount":1022,"publisher":{"@id":"https:\/\/office-roxx.de\/buero-bewegung\/#organization"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/","url":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/","name":"Beim bewegten Arbeiten herrscht Stillstand &#8211; BEWEGUNG IM B\u00dcRO","isPartOf":{"@id":"https:\/\/office-roxx.de\/buero-bewegung\/#website"},"datePublished":"2022-06-13T04:35:53+00:00","breadcrumb":{"@id":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/office-roxx.de\/buero-bewegung\/beim-bewegten-arbeiten-herrscht-stillstand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/office-roxx.de\/buero-bewegung\/"},{"@type":"ListItem","position":2,"name":"Beim bewegten Arbeiten herrscht Stillstand"}]},{"@type":"WebSite","@id":"https:\/\/office-roxx.de\/buero-bewegung\/#website","url":"https:\/\/office-roxx.de\/buero-bewegung\/","name":"BEWEGUNG IM B\u00dcRO","description":"","publisher":{"@id":"https:\/\/office-roxx.de\/buero-bewegung\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/office-roxx.de\/buero-bewegung\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/office-roxx.de\/buero-bewegung\/#organization","name":"Bewegung im B\u00fcro","url":"https:\/\/office-roxx.de\/buero-bewegung\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/office-roxx.de\/buero-bewegung\/#\/schema\/logo\/image\/","url":"https:\/\/office-roxx.de\/buero-bewegung\/wp-content\/uploads\/2020\/01\/Bewegung.jpg","contentUrl":"https:\/\/office-roxx.de\/buero-bewegung\/wp-content\/uploads\/2020\/01\/Bewegung.jpg","width":999,"height":520,"caption":"Bewegung im B\u00fcro"},"image":{"@id":"https:\/\/office-roxx.de\/buero-bewegung\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/office-roxx.de\/buero-bewegung\/#\/schema\/person\/1fb790e36fc2c425645a8d6bdd301799","name":"Team-BB"}]}},"_links":{"self":[{"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/posts\/4815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/comments?post=4815"}],"version-history":[{"count":8,"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/posts\/4815\/revisions"}],"predecessor-version":[{"id":4823,"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/posts\/4815\/revisions\/4823"}],"wp:attachment":[{"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/media?parent=4815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/categories?post=4815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/office-roxx.de\/buero-bewegung\/wp-json\/wp\/v2\/tags?post=4815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}